{"id":11062,"date":"2021-10-13T16:06:40","date_gmt":"2021-10-13T14:06:40","guid":{"rendered":"https:\/\/nect.com\/?p=11062"},"modified":"2026-07-14T14:51:53","modified_gmt":"2026-07-14T12:51:53","slug":"nect-gmbh-poursuit-son-expansion-en-europe","status":"publish","type":"post","link":"https:\/\/nect.com\/fr\/media\/actualites\/nect-gmbh-poursuit-son-expansion-en-europe\/","title":{"rendered":"Nect GmbH poursuit son expansion en Europe"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"11062\" class=\"elementor elementor-11062 elementor-11059\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cde6646 e-flex e-con-boxed e-con e-parent\" data-id=\"cde6646\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f786a68 elementor-widget elementor-widget-text-editor\" data-id=\"f786a68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>L\u2019entreprise hambourgeoise propose d\u00e9sormais la proc\u00e9dure Selfie-Ident \u00e9galement en Espagne et en Pologne<\/li><li>CEO et fondateur Benny Bennet J\u00fcrgens : \u00ab L\u2019expansion au sein de l\u2019UE est la prochaine \u00e9tape logique. Ici, nous avons des avantages significatifs gr\u00e2ce \u00e0 la certification eIDAS. \u00bb <\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9c99b8 elementor-widget elementor-widget-text-editor\" data-id=\"b9c99b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Hambourg, 13.10.2021<\/strong> Nect goes Europe : Nect Selfie-Ident, la solution innovante d\u2019identification en ligne enti\u00e8rement automatis\u00e9e bas\u00e9e sur l\u2019intelligence artificielle, est d\u00e9sormais disponible en Espagne et en Pologne. Dans ces deux march\u00e9s europ\u00e9ens importants, la soci\u00e9t\u00e9 hambourgeoise Nect GmbH a maintenant commenc\u00e9 \u00e0 mettre en place une organisation commerciale. Les deux nouveaux Country Managers Ruben Levy Benseft (Espagne) et Matthias Lukiewicz (Pologne) en sont les principaux responsables. En ao\u00fbt, l\u2019entreprise fond\u00e9e il y a quatre ans avait entam\u00e9 son expansion \u00e0 l\u2019\u00e9tranger avec un partenariat de distribution en Autriche. D\u2019autres pays devraient suivre prochainement.    <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-890c08b elementor-widget elementor-widget-text-editor\" data-id=\"890c08b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tRuben Levy Benseft dispose de nombreuses ann\u00e9es d\u2019exp\u00e9rience dans la finance et la fintech. Il a commenc\u00e9 sa carri\u00e8re en 2012 au sein d\u2019une entreprise du groupe BNP Paribas. Au cours de ses \u00e9tapes professionnelles suivantes chez Paypal et Klarna, il a pu acqu\u00e9rir une grande expertise dans le domaine des syst\u00e8mes de paiement. En 2017, Levy Benseft a r\u00e9alis\u00e9 son souhait d\u2019entreprendre et a fond\u00e9, avec cinq autres personnes, l\u2019entreprise SaaS espagnole Coinscrap, dont les applications offrent aux utilisateurs des solutions pour optimiser leurs finances personnelles. Depuis ao\u00fbt, il travaille pour la soci\u00e9t\u00e9 hambourgeoise Nect GmbH en tant que Country Manager en Espagne.    \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e4ef44 elementor-widget elementor-widget-text-editor\" data-id=\"2e4ef44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\u00ab Mon objectif est de faire de Nect la r\u00e9f\u00e9rence des proc\u00e9dures d\u2019identification num\u00e9rique en Espagne \u2013 aussi bien pour les banques et les assurances que pour l\u2019administration publique \u00bb, d\u00e9clare Ruben Lev Benseft. \u00ab C\u2019est pour moi un nouveau d\u00e9fi d\u2019implanter sur le march\u00e9 espagnol un prestataire allemand de services de confiance en forte croissance, et mes connaissances approfondies de l\u2019\u00e9cosyst\u00e8me existant m\u2019y aideront. \u00bb \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d268eb elementor-widget elementor-widget-text-editor\" data-id=\"5d268eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tMatthias Lukiewicz peut se pr\u00e9valoir de nombreuses ann\u00e9es d\u2019exp\u00e9rience internationale dans le secteur de l\u2019assurance et dans l\u2019IT. Apr\u00e8s 15 ans pass\u00e9s dans diff\u00e9rentes compagnies d\u2019assurance, ce Polonais de naissance, install\u00e9 \u00e0 Cologne, a rejoint le secteur IT en 2009. En 2015, il a pu placer, avec une entreprise IT allemande, un grand projet logiciel aupr\u00e8s de la plus grande entreprise ferroviaire polonaise. Depuis, il vit et travaille en Pologne. Pour des \u00e9diteurs de logiciels polonais, il a accompagn\u00e9 des clients en Allemagne, en Autriche et en Suisse. Depuis septembre, Matthias Lukiewicz est bas\u00e9 \u00e0 Varsovie et travaille pour Nect GmbH en tant que Country Manager Poland.     \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0426bce elementor-widget elementor-widget-text-editor\" data-id=\"0426bce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\u00ab Nect r\u00e9unit les personnes et l\u2019innovation technologique et conna\u00eet un grand succ\u00e8s en Allemagne. C\u2019est aussi ce que je veux atteindre sur le march\u00e9 polonais \u00bb, d\u00e9clare Matthias Lukiewicz. \u00ab Comme pour toute expansion sur un nouveau march\u00e9, l\u2019objectif le plus important est d\u2019\u00eatre pr\u00e9sent et de gagner de nouveaux clients. Je suis certain d\u2019y parvenir gr\u00e2ce \u00e0 ma connaissance de longue date et approfondie du march\u00e9 polonais \u2013 bien s\u00fbr avec le soutien de mes futurs coll\u00e8gues en Pologne. \u00bb   \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ebebf9 elementor-widget elementor-widget-text-editor\" data-id=\"6ebebf9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tBenny Bennet J\u00fcrgens, cofondateur et CEO de Nect GmbH : \u00ab Depuis la cr\u00e9ation de Nect en 2017, nous nous sommes impos\u00e9s avec succ\u00e8s sur le march\u00e9 allemand. Entre-temps, de nombreuses entreprises de renom utilisent notre solution, comme par exemple l\u2019assurance R+V, la Barmer et Telekom. Nous sommes maintenant pr\u00eats pour la prochaine \u00e9tape logique : l\u2019expansion dans les pays de l\u2019UE, o\u00f9 nous disposons d\u2019avantages significatifs gr\u00e2ce \u00e0 la certification eIDAS. Avec nos deux Country Managers, nous avons pu recruter des collaborateurs exp\u00e9riment\u00e9s, solidement ancr\u00e9s dans leur march\u00e9 respectif et dot\u00e9s de l\u2019esprit de fondateur qui caract\u00e9rise tous les collaborateurs de Nect. En outre, depuis Hambourg, nous pouvons soutenir les deux nouveaux collaborateurs gr\u00e2ce \u00e0 notre exp\u00e9rience des exigences et r\u00e9glementations pertinentes \u00e0 l\u2019\u00e9chelle de l\u2019UE. \u00bb    \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2f645b elementor-widget elementor-widget-heading\" data-id=\"a2f645b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Confirmation d\u2019identit\u00e9 en ligne rapide, s\u00fbre et simple<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae897cc elementor-widget elementor-widget-text-editor\" data-id=\"ae897cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tNect Selfie-Ident repose sur la technologie Robo-Ident de Nect, brevet\u00e9e et certifi\u00e9e en tant que module de service de confiance (eIDAS). Les clients de ces entreprises peuvent s\u2019identifier num\u00e9riquement avec l\u2019application Nect, \u00e0 tout moment et en tout lieu, sans temps d\u2019attente, et n\u2019ont besoin que d\u2019un document d\u2019identit\u00e9 et d\u2019un smartphone. Une capture du document d\u2019identit\u00e9 et une reconnaissance faciale via une vid\u00e9o selfie garantissent notamment que la personne et le document correspondent. Diff\u00e9rents contr\u00f4les de s\u00e9curit\u00e9, par exemple la lecture des hologrammes, permettent de d\u00e9tecter \u00e0 100 % les tentatives de fraude par le pass\u00e9 et d\u2019emp\u00eacher ainsi la fraude. La solution Nect est en principe compatible avec des documents d\u2019identit\u00e9 provenant de presque tous les pays du monde.    \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-de92d5a e-flex e-con-boxed e-con e-parent\" data-id=\"de92d5a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d196a27 elementor-widget elementor-widget-spacer\" data-id=\"d196a27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1b655e9 e-flex e-con-boxed e-con e-parent\" data-id=\"1b655e9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-63b7e50 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"63b7e50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/nect.com\/fr\/presse\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Retour \u00e0 l\u2019aper\u00e7u<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Nect goes Europe : Nect Selfie-Ident, la solution innovante d\u2019identification en ligne enti\u00e8rement automatis\u00e9e bas\u00e9e sur l\u2019intelligence artificielle, est d\u00e9sormais disponible en Espagne et en Pologne. Dans ces deux march\u00e9s europ\u00e9ens importants, la soci\u00e9t\u00e9 hambourgeoise Nect GmbH a maintenant commenc\u00e9 \u00e0 mettre en place une organisation commerciale. <\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[135],"tags":[],"class_list":["post-11062","post","type-post","status-publish","format-standard","hentry","category-actualites"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nect GmbH poursuit son expansion en Europe<\/title>\n<meta name=\"description\" content=\"Nect propose d\u00e9sormais la proc\u00e9dure Selfie-Ident \u00e9galement en Espagne et en Pologne. \u00ab Ici, nous avons des avantages significatifs gr\u00e2ce \u00e0 la certification eIDAS. \u00bb\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nect.com\/fr\/media\/actualites\/nect-gmbh-poursuit-son-expansion-en-europe\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nect GmbH poursuit son expansion en Europe\" \/>\n<meta property=\"og:description\" content=\"Nect propose d\u00e9sormais la proc\u00e9dure Selfie-Ident \u00e9galement en Espagne et en Pologne. \u00ab Ici, nous avons des avantages significatifs gr\u00e2ce \u00e0 la certification eIDAS. \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nect.com\/fr\/media\/actualites\/nect-gmbh-poursuit-son-expansion-en-europe\/\" \/>\n<meta property=\"og:site_name\" content=\"Nect\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NiceToNectYou\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-13T14:06:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T12:51:53+00:00\" \/>\n<meta name=\"author\" content=\"Martin Nahrgang\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@nicetonectyou\" \/>\n<meta name=\"twitter:site\" content=\"@nicetonectyou\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martin Nahrgang\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nect.com\\\/fr\\\/media\\\/actualites\\\/nect-gmbh-poursuit-son-expansion-en-europe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nect.com\\\/fr\\\/media\\\/actualites\\\/nect-gmbh-poursuit-son-expansion-en-europe\\\/\"},\"author\":{\"name\":\"Martin Nahrgang\",\"@id\":\"https:\\\/\\\/nect.com\\\/fr\\\/#\\\/schema\\\/person\\\/eefaec74b5565e0f6fcd4a27ca30b863\"},\"headline\":\"Nect GmbH poursuit son expansion en Europe\",\"datePublished\":\"2021-10-13T14:06:40+00:00\",\"dateModified\":\"2026-07-14T12:51:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nect.com\\\/fr\\\/media\\\/actualites\\\/nect-gmbh-poursuit-son-expansion-en-europe\\\/\"},\"wordCount\":839,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/nect.com\\\/fr\\\/#organization\"},\"articleSection\":[\"Actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/nect.com\\\/fr\\\/media\\\/actualites\\\/nect-gmbh-poursuit-son-expansion-en-europe\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nect.com\\\/fr\\\/media\\\/actualites\\\/nect-gmbh-poursuit-son-expansion-en-europe\\\/\",\"url\":\"https:\\\/\\\/nect.com\\\/fr\\\/media\\\/actualites\\\/nect-gmbh-poursuit-son-expansion-en-europe\\\/\",\"name\":\"Nect GmbH poursuit son expansion en Europe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nect.com\\\/fr\\\/#website\"},\"datePublished\":\"2021-10-13T14:06:40+00:00\",\"dateModified\":\"2026-07-14T12:51:53+00:00\",\"description\":\"Nect propose d\u00e9sormais la proc\u00e9dure Selfie-Ident \u00e9galement en Espagne et en Pologne. \u00ab Ici, nous avons des avantages significatifs gr\u00e2ce \u00e0 la certification eIDAS. \u00bb\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nect.com\\\/fr\\\/media\\\/actualites\\\/nect-gmbh-poursuit-son-expansion-en-europe\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nect.com\\\/fr\\\/media\\\/actualites\\\/nect-gmbh-poursuit-son-expansion-en-europe\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nect.com\\\/fr\\\/media\\\/actualites\\\/nect-gmbh-poursuit-son-expansion-en-europe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/nect.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nect GmbH poursuit son expansion en Europe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nect.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/nect.com\\\/fr\\\/\",\"name\":\"Nect\",\"description\":\"Built for the future of digital identity.\",\"publisher\":{\"@id\":\"https:\\\/\\\/nect.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nect.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nect.com\\\/fr\\\/#organization\",\"name\":\"Nect\",\"url\":\"https:\\\/\\\/nect.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nect.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nect.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Nect_favicon_App.svg\",\"contentUrl\":\"https:\\\/\\\/nect.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Nect_favicon_App.svg\",\"width\":512,\"height\":512,\"caption\":\"Nect\"},\"image\":{\"@id\":\"https:\\\/\\\/nect.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NiceToNectYou\\\/\",\"https:\\\/\\\/x.com\\\/nicetonectyou\",\"https:\\\/\\\/www.instagram.com\\\/nect\\\/\",\"https:\\\/\\\/vimeo.com\\\/nect\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/nect.com\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nect.com\\\/fr\\\/#\\\/schema\\\/person\\\/eefaec74b5565e0f6fcd4a27ca30b863\",\"name\":\"Martin Nahrgang\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nect.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b578aea64bf9ac66cf254eaa88662082.jpg?ver=1784059516\",\"url\":\"https:\\\/\\\/nect.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b578aea64bf9ac66cf254eaa88662082.jpg?ver=1784059516\",\"contentUrl\":\"https:\\\/\\\/nect.com\\\/wp-content\\\/litespeed\\\/avatar\\\/b578aea64bf9ac66cf254eaa88662082.jpg?ver=1784059516\",\"caption\":\"Martin Nahrgang\"},\"description\":\"Marketing Manager\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nect GmbH poursuit son expansion en Europe","description":"Nect propose d\u00e9sormais la proc\u00e9dure Selfie-Ident \u00e9galement en Espagne et en Pologne. \u00ab Ici, nous avons des avantages significatifs gr\u00e2ce \u00e0 la certification eIDAS. \u00bb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nect.com\/fr\/media\/actualites\/nect-gmbh-poursuit-son-expansion-en-europe\/","og_locale":"fr_FR","og_type":"article","og_title":"Nect GmbH poursuit son expansion en Europe","og_description":"Nect propose d\u00e9sormais la proc\u00e9dure Selfie-Ident \u00e9galement en Espagne et en Pologne. \u00ab Ici, nous avons des avantages significatifs gr\u00e2ce \u00e0 la certification eIDAS. \u00bb","og_url":"https:\/\/nect.com\/fr\/media\/actualites\/nect-gmbh-poursuit-son-expansion-en-europe\/","og_site_name":"Nect","article_publisher":"https:\/\/www.facebook.com\/NiceToNectYou\/","article_published_time":"2021-10-13T14:06:40+00:00","article_modified_time":"2026-07-14T12:51:53+00:00","author":"Martin Nahrgang","twitter_card":"summary_large_image","twitter_creator":"@nicetonectyou","twitter_site":"@nicetonectyou","twitter_misc":{"\u00c9crit par":"Martin Nahrgang","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nect.com\/fr\/media\/actualites\/nect-gmbh-poursuit-son-expansion-en-europe\/#article","isPartOf":{"@id":"https:\/\/nect.com\/fr\/media\/actualites\/nect-gmbh-poursuit-son-expansion-en-europe\/"},"author":{"name":"Martin Nahrgang","@id":"https:\/\/nect.com\/fr\/#\/schema\/person\/eefaec74b5565e0f6fcd4a27ca30b863"},"headline":"Nect GmbH poursuit son expansion en Europe","datePublished":"2021-10-13T14:06:40+00:00","dateModified":"2026-07-14T12:51:53+00:00","mainEntityOfPage":{"@id":"https:\/\/nect.com\/fr\/media\/actualites\/nect-gmbh-poursuit-son-expansion-en-europe\/"},"wordCount":839,"commentCount":0,"publisher":{"@id":"https:\/\/nect.com\/fr\/#organization"},"articleSection":["Actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/nect.com\/fr\/media\/actualites\/nect-gmbh-poursuit-son-expansion-en-europe\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/nect.com\/fr\/media\/actualites\/nect-gmbh-poursuit-son-expansion-en-europe\/","url":"https:\/\/nect.com\/fr\/media\/actualites\/nect-gmbh-poursuit-son-expansion-en-europe\/","name":"Nect GmbH poursuit son expansion en Europe","isPartOf":{"@id":"https:\/\/nect.com\/fr\/#website"},"datePublished":"2021-10-13T14:06:40+00:00","dateModified":"2026-07-14T12:51:53+00:00","description":"Nect propose d\u00e9sormais la proc\u00e9dure Selfie-Ident \u00e9galement en Espagne et en Pologne. \u00ab Ici, nous avons des avantages significatifs gr\u00e2ce \u00e0 la certification eIDAS. \u00bb","breadcrumb":{"@id":"https:\/\/nect.com\/fr\/media\/actualites\/nect-gmbh-poursuit-son-expansion-en-europe\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nect.com\/fr\/media\/actualites\/nect-gmbh-poursuit-son-expansion-en-europe\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nect.com\/fr\/media\/actualites\/nect-gmbh-poursuit-son-expansion-en-europe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/nect.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Nect GmbH poursuit son expansion en Europe"}]},{"@type":"WebSite","@id":"https:\/\/nect.com\/fr\/#website","url":"https:\/\/nect.com\/fr\/","name":"Nect","description":"Built for the future of digital identity.","publisher":{"@id":"https:\/\/nect.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nect.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/nect.com\/fr\/#organization","name":"Nect","url":"https:\/\/nect.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nect.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/nect.com\/wp-content\/uploads\/2025\/05\/Nect_favicon_App.svg","contentUrl":"https:\/\/nect.com\/wp-content\/uploads\/2025\/05\/Nect_favicon_App.svg","width":512,"height":512,"caption":"Nect"},"image":{"@id":"https:\/\/nect.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NiceToNectYou\/","https:\/\/x.com\/nicetonectyou","https:\/\/www.instagram.com\/nect\/","https:\/\/vimeo.com\/nect\/","https:\/\/www.linkedin.com\/company\/nect.com"]},{"@type":"Person","@id":"https:\/\/nect.com\/fr\/#\/schema\/person\/eefaec74b5565e0f6fcd4a27ca30b863","name":"Martin Nahrgang","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nect.com\/wp-content\/litespeed\/avatar\/b578aea64bf9ac66cf254eaa88662082.jpg?ver=1784059516","url":"https:\/\/nect.com\/wp-content\/litespeed\/avatar\/b578aea64bf9ac66cf254eaa88662082.jpg?ver=1784059516","contentUrl":"https:\/\/nect.com\/wp-content\/litespeed\/avatar\/b578aea64bf9ac66cf254eaa88662082.jpg?ver=1784059516","caption":"Martin Nahrgang"},"description":"Marketing Manager"}]}},"_links":{"self":[{"href":"https:\/\/nect.com\/fr\/wp-json\/wp\/v2\/posts\/11062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nect.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nect.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nect.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/nect.com\/fr\/wp-json\/wp\/v2\/comments?post=11062"}],"version-history":[{"count":2,"href":"https:\/\/nect.com\/fr\/wp-json\/wp\/v2\/posts\/11062\/revisions"}],"predecessor-version":[{"id":12451,"href":"https:\/\/nect.com\/fr\/wp-json\/wp\/v2\/posts\/11062\/revisions\/12451"}],"wp:attachment":[{"href":"https:\/\/nect.com\/fr\/wp-json\/wp\/v2\/media?parent=11062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nect.com\/fr\/wp-json\/wp\/v2\/categories?post=11062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nect.com\/fr\/wp-json\/wp\/v2\/tags?post=11062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}